{"id":52878,"date":"2017-04-29T10:43:03","date_gmt":"2017-04-29T10:43:03","guid":{"rendered":"https:\/\/mattfaces.nl\/men\/"},"modified":"2025-12-16T19:40:37","modified_gmt":"2025-12-16T19:40:37","slug":"men","status":"publish","type":"page","link":"https:\/\/mattfaces.nl\/en\/men\/","title":{"rendered":"Men"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-padding-bottom:0px;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-first\" style=\"--awb-bg-size:cover;width:22%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-one-fourth\" style=\"--awb-bg-size:cover;width:22%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><pre style=\"text-align: center;\"><a class=\"\" href=\"http:\/\/mattfaces.nl\/en\/faces-women\/\">Women<\/a><\/pre>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_4 1_4 fusion-one-fourth\" style=\"--awb-bg-size:cover;width:22%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-2\"><pre style=\"text-align: center;\"><strong><a class=\"modelClassActive\" href=\"http:\/\/www.mattfaces.nl\/en\/men-faces\">Men<\/a><\/strong><\/pre>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"--awb-bg-size:cover;width:22%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-padding-bottom:20px;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:20px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -20px !important; margin-right:-20px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-no-meta-info fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope\" data-pages=\"0\" data-grid-col-space=\"40\" style=\"margin: -20px -20px 0;min-height:500px;\"><article id=\"blog-1-post-57383\" class=\"fusion-post-grid post-57383 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1001\" height=\"1342\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2021\/11\/large-1689671745-402e19a5b1d2d542f129e5e8170eb42b-e1689671968533.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/ahmed\/\">\n\t\t\t\t\t\tAhmed (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/ahmed\/\" aria-label=\"Ahmed (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/ahmed\/\">Ahmed (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55993\" class=\"fusion-post-grid post-55993 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f-400x600.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f-600x900.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f-800x1200.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1770272394-2d925c2d646fff176c1a7df83995523f.jpg 833w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-3\/\">\n\t\t\t\t\t\tAlessio Wilms *international\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-3\/\" aria-label=\"Alessio Wilms *international\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-3\/\">Alessio Wilms *international<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55351\" class=\"fusion-post-grid post-55351 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"834\" height=\"1190\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/08\/32-bob-van-der-hoek-main-book-e1722843774977.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/bobvanderhoek\/\">\n\t\t\t\t\t\tBob van der Hoek *out of town\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/bobvanderhoek\/\" aria-label=\"Bob van der Hoek *out of town\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/bobvanderhoek\/\">Bob van der Hoek *out of town<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-59289\" class=\"fusion-post-grid post-59289 post type-post status-publish format-standard has-post-thumbnail hentry category-classic category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny-200x250.jpeg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny-400x500.jpeg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny-600x750.jpeg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny-800x1000.jpeg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/08\/1-bas-zijlstra-manny.jpeg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/bas-z\/\">\n\t\t\t\t\t\tBas Z\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/bas-z\/\" aria-label=\"Bas Z\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/bas-z\/\">Bas Z<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55742\" class=\"fusion-post-grid post-55742 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"817\" height=\"1230\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145-200x301.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145-400x602.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145-600x903.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145-800x1204.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/11\/MAN2561-e1750068553145.jpg 817w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/bobvanrutte\/\">\n\t\t\t\t\t\tBob van Rutte\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/bobvanrutte\/\" aria-label=\"Bob van Rutte\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/bobvanrutte\/\">Bob van Rutte<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-54779\" class=\"fusion-post-grid post-54779 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"893\" height=\"1027\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574-200x230.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574-400x460.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574-600x690.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574-800x920.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/01\/large-1760342208-73b05063bd8397d335ea9318c96f193d-e1760342456574.jpg 893w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/coen\/\">\n\t\t\t\t\t\tCoen K\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/coen\/\" aria-label=\"Coen K\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/coen\/\">Coen K<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-63566\" class=\"fusion-post-grid post-63566 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"999\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book-200x250.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book-400x501.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book-600x751.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book-800x1001.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/03\/1-christian-becker-main-book.jpg 999w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/bauke-2\/\">\n\t\t\t\t\t\tBauke\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/bauke-2\/\" aria-label=\"Bauke\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/bauke-2\/\">Bauke<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58345\" class=\"fusion-post-grid post-58345 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1589\" height=\"1794\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2024-06-20-at-15.58.49-e1718963281894.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/bruno\/\">\n\t\t\t\t\t\tBruno P\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/bruno\/\" aria-label=\"Bruno P\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/bruno\/\">Bruno P<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55611\" class=\"fusion-post-grid post-55611 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"997\" height=\"1470\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/03\/large-1725532500-28487a8701c569ea808c060057ea568a-e1734445952439.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/beau\/\">\n\t\t\t\t\t\tBeau Thomas\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/beau\/\" aria-label=\"Beau Thomas\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/beau\/\">Beau Thomas<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-59060\" class=\"fusion-post-grid post-59060 post type-post status-publish format-standard has-post-thumbnail hentry category-faces-men category-specials\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/05\/large-1642328235-4289877c5924014e8169a5761dcf905e.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/05\/large-1642328235-4289877c5924014e8169a5761dcf905e-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/05\/large-1642328235-4289877c5924014e8169a5761dcf905e.jpg 667w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/chris\/\">\n\t\t\t\t\t\tChris H\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/chris\/\" aria-label=\"Chris H\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/chris\/\">Chris H<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55699\" class=\"fusion-post-grid post-55699 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"608\" height=\"720\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/01\/3-cornelis-dekker-house-of-einstein-e1746092083340.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/01\/3-cornelis-dekker-house-of-einstein-e1746092083340-200x237.jpeg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/01\/3-cornelis-dekker-house-of-einstein-e1746092083340-400x474.jpeg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/01\/3-cornelis-dekker-house-of-einstein-e1746092083340-600x711.jpeg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/01\/3-cornelis-dekker-house-of-einstein-e1746092083340.jpeg 608w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/cornelis\/\">\n\t\t\t\t\t\tCornelis Dekker\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/cornelis\/\" aria-label=\"Cornelis Dekker\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/cornelis\/\">Cornelis Dekker<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-61166\" class=\"fusion-post-grid post-61166 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"518\" height=\"704\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/02\/image00033-e1770391457457.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/cornelis-2\/\">\n\t\t\t\t\t\tCornelis Dekker\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/cornelis-2\/\" aria-label=\"Cornelis Dekker\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/cornelis-2\/\">Cornelis Dekker<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-57143\" class=\"fusion-post-grid post-57143 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b-200x250.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b-400x500.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b-600x750.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b-800x1000.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/05\/large-1752233714-5d2d323cbfa756e57413645318ba365b.jpg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/francesco\/\">\n\t\t\t\t\t\tFrancesco D\u2019Aquino\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/francesco\/\" aria-label=\"Francesco D\u2019Aquino\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/francesco\/\">Francesco D\u2019Aquino<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-56779\" class=\"fusion-post-grid post-56779 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"850\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/01\/hugues-malvoti-20241016-immbxl5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/01\/hugues-malvoti-20241016-immbxl5-200x283.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/01\/hugues-malvoti-20241016-immbxl5-400x567.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/01\/hugues-malvoti-20241016-immbxl5.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/hugues\/\">\n\t\t\t\t\t\tHugues\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/hugues\/\" aria-label=\"Hugues\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/hugues\/\">Hugues<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58360\" class=\"fusion-post-grid post-58360 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"1421\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/08\/large-1681985814-38b6f13573274260d48a49b6b9e50c55-e1734446442495.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/jason\/\">\n\t\t\t\t\t\tJason F (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/jason\/\" aria-label=\"Jason F (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/jason\/\">Jason F (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-53736\" class=\"fusion-post-grid post-53736 post type-post status-publish format-standard has-post-thumbnail hentry category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037-200x250.jpeg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037-400x500.jpeg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037-600x750.jpeg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037-800x1000.jpeg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/05\/image00037.jpeg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/ibrahim\/\">\n\t\t\t\t\t\tIbrahim\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/ibrahim\/\" aria-label=\"Ibrahim\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/ibrahim\/\">Ibrahim<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58201\" class=\"fusion-post-grid post-58201 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"1350\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/06\/20190417_090755115_M.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/jimmyj\/\">\n\t\t\t\t\t\tJimmy J\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/jimmyj\/\" aria-label=\"Jimmy J\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/jimmyj\/\">Jimmy J<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58644\" class=\"fusion-post-grid post-58644 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2580\" height=\"3737\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/03\/13-joachim-sleper-nico-quinteros-e1735812031395.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/joachim\/\">\n\t\t\t\t\t\tJoachim Sleper\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/joachim\/\" aria-label=\"Joachim Sleper\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/joachim\/\">Joachim Sleper<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-60471\" class=\"fusion-post-grid post-60471 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"938\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book-200x267.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book-400x533.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book-600x800.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book-800x1066.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/01\/1-jonas-a-main-book.jpg 938w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/jort-2\/\">\n\t\t\t\t\t\tJort\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/jort-2\/\" aria-label=\"Jort\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/jort-2\/\">Jort<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58354\" class=\"fusion-post-grid post-58354 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"780\" height=\"999\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/08\/large-1709725842-94f46f0defede878b10cdb7378d08fb4-e1734447944236.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/joshua\/\">\n\t\t\t\t\t\tJoshua (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/joshua\/\" aria-label=\"Joshua (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/joshua\/\">Joshua (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-57174\" class=\"fusion-post-grid post-57174 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1500\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/03\/LASZLO_TEST_11.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/03\/LASZLO_TEST_11-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/03\/LASZLO_TEST_11.jpg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/laszlo\/\">\n\t\t\t\t\t\tLaszlo Huiber\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/laszlo\/\" aria-label=\"Laszlo Huiber\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/laszlo\/\">Laszlo Huiber<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55363\" class=\"fusion-post-grid post-55363 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"1413\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/16-liniel-emanuels-main-book-e1720552395573.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/liniel\/\">\n\t\t\t\t\t\tLiniel\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/liniel\/\" aria-label=\"Liniel\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/liniel\/\">Liniel<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-59245\" class=\"fusion-post-grid post-59245 post type-post status-publish format-standard has-post-thumbnail hentry category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions-400x600.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions-600x900.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions-800x1200.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2018\/01\/4-karog-siniaki-malelions.jpg 833w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/karog-international\/\">\n\t\t\t\t\t\tKarog\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/karog-international\/\" aria-label=\"Karog\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/karog-international\/\">Karog<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58656\" class=\"fusion-post-grid post-58656 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb-400x600.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb-600x900.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb-800x1200.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/01\/large-1746608953-bd965d3a33d61493f278113db7d549eb.jpg 833w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/manuel\/\">\n\t\t\t\t\t\tManuel\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/manuel\/\" aria-label=\"Manuel\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/manuel\/\">Manuel<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58351\" class=\"fusion-post-grid post-58351 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"888\" height=\"1083\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/08\/marlon-sackey-73524-e1566893501233.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/marlon\/\">\n\t\t\t\t\t\tMarlon S (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/marlon\/\" aria-label=\"Marlon S (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/marlon\/\">Marlon S (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55723\" class=\"fusion-post-grid post-55723 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"846\" height=\"1154\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/12\/large-1702644798-1f821902c2b9c546536a4a3808f7f8fe-e1734004982239.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/marcel\/\">\n\t\t\t\t\t\tMarcel K (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/marcel\/\" aria-label=\"Marcel K (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/marcel\/\">Marcel K (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-56242\" class=\"fusion-post-grid post-56242 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1117\" height=\"1500\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/08\/large-1684758639-cfdad613965f326bdded9e876ec7ee95.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/micah\/\">\n\t\t\t\t\t\tMicah (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/micah\/\" aria-label=\"Micah (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/micah\/\">Micah (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-53651\" class=\"fusion-post-grid post-53651 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-fashion-men category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"619\" height=\"770\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/11\/000001100010-e1764320414873.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/11\/000001100010-e1764320414873-200x249.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/11\/000001100010-e1764320414873-400x498.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/11\/000001100010-e1764320414873-600x746.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/11\/000001100010-e1764320414873.jpg 619w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/noud\/\">\n\t\t\t\t\t\tNoud (out of town)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/noud\/\" aria-label=\"Noud (out of town)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/noud\/\">Noud (out of town)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58348\" class=\"fusion-post-grid post-58348 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1586\" height=\"1982\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777-200x250.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777-400x500.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777-600x750.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777-800x1000.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777-1200x1500.jpg 1200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/IMG_7777.jpg 1586w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/pedro\/\">\n\t\t\t\t\t\tPedro S (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/pedro\/\" aria-label=\"Pedro S (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/pedro\/\">Pedro S (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-61300\" class=\"fusion-post-grid post-61300 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close-200x300.jpeg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close-400x600.jpeg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close-600x900.jpeg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close-800x1200.jpeg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2026\/04\/HEADSHOT_opener_CLDSC_2333_V2_bw_close.jpeg 833w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-4\/\">\n\t\t\t\t\t\tAlessio Wilms *international\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-4\/\" aria-label=\"Alessio Wilms *international\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/alessiowilms-4\/\">Alessio Wilms *international<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-56227\" class=\"fusion-post-grid post-56227 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"999\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670-200x250.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670-400x501.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670-600x751.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670-800x1001.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/10\/large-1716884567-e4596fde8a60dccc520c1688cd55b670.jpg 999w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/quinn\/\">\n\t\t\t\t\t\tQuinn\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/quinn\/\" aria-label=\"Quinn\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/quinn\/\">Quinn<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58191\" class=\"fusion-post-grid post-58191 post type-post status-publish format-standard has-post-thumbnail hentry category-classic category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"752\" height=\"968\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/07\/large-1726564067-cb889774ea27f8d9b87e217abc74a508-e1747043378752.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/07\/large-1726564067-cb889774ea27f8d9b87e217abc74a508-e1747043378752-200x257.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/07\/large-1726564067-cb889774ea27f8d9b87e217abc74a508-e1747043378752-400x515.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/07\/large-1726564067-cb889774ea27f8d9b87e217abc74a508-e1747043378752-600x772.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/07\/large-1726564067-cb889774ea27f8d9b87e217abc74a508-e1747043378752.jpg 752w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/ryan\/\">\n\t\t\t\t\t\tRyan Lovelock\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/ryan\/\" aria-label=\"Ryan Lovelock\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/ryan\/\">Ryan Lovelock<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-59280\" class=\"fusion-post-grid post-59280 post type-post status-publish format-standard has-post-thumbnail hentry category-faces-men category-specials\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1498\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/09\/tempImageCx00iM.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/09\/tempImageCx00iM-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2017\/09\/tempImageCx00iM.jpg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/reno\/\">\n\t\t\t\t\t\tReno\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/reno\/\" aria-label=\"Reno\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/reno\/\">Reno<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-56782\" class=\"fusion-post-grid post-56782 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"850\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/01\/6-sam-cornand-main-book.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/sam-c\/\">\n\t\t\t\t\t\tSam C\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/sam-c\/\" aria-label=\"Sam C\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/sam-c\/\">Sam C<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-57984\" class=\"fusion-post-grid post-57984 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/11\/large-1655906675-409420422839d74591fc32f3d18654fd.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/11\/large-1655906675-409420422839d74591fc32f3d18654fd-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2020\/11\/large-1655906675-409420422839d74591fc32f3d18654fd.jpg 667w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/sander\/\">\n\t\t\t\t\t\tSander Hoeksma\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/sander\/\" aria-label=\"Sander Hoeksma\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/sander\/\">Sander Hoeksma<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58342\" class=\"fusion-post-grid post-58342 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"865\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5-200x289.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5-400x578.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5-600x867.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5-800x1156.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/09\/mf007201753m_165803_5.jpg 865w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/stefan\/\">\n\t\t\t\t\t\tStefan Scheenstra\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/stefan\/\" aria-label=\"Stefan Scheenstra\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/stefan\/\">Stefan Scheenstra<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-58333\" class=\"fusion-post-grid post-58333 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"690\" height=\"973\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2019\/11\/large-1706540052-dedc01d9985b9394f5bbb51757cdd2c9-e1706540232140.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/teddy-2\/\">\n\t\t\t\t\t\tTeddy\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/teddy-2\/\" aria-label=\"Teddy\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/teddy-2\/\">Teddy<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-56370\" class=\"fusion-post-grid post-56370 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"833\" height=\"1250\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/04\/2-uriah-main-book.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/04\/2-uriah-main-book-200x300.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2023\/04\/2-uriah-main-book.jpg 833w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/uriah\/\">\n\t\t\t\t\t\tUriah (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/uriah\/\" aria-label=\"Uriah (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/uriah\/\">Uriah (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-57137\" class=\"fusion-post-grid post-57137 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"730\" height=\"950\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2022\/06\/large-1655887400-a70f98fd76e25477d8de3bd23293d0d9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/victor\/\">\n\t\t\t\t\t\tVictor (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/victor\/\" aria-label=\"Victor (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/victor\/\">Victor (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-54257\" class=\"fusion-post-grid post-54257 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-fashion-men category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"835\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/03\/large-1769527173-9206c85ebca281b8f0d63bedbef05b24-e1778490140663.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/03\/large-1769527173-9206c85ebca281b8f0d63bedbef05b24-e1778490140663-200x232.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/03\/large-1769527173-9206c85ebca281b8f0d63bedbef05b24-e1778490140663-400x464.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/03\/large-1769527173-9206c85ebca281b8f0d63bedbef05b24-e1778490140663-600x696.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/03\/large-1769527173-9206c85ebca281b8f0d63bedbef05b24-e1778490140663.jpg 720w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/ritsedejong\/\">\n\t\t\t\t\t\tRitse de Jong\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/ritsedejong\/\" aria-label=\"Ritse de Jong\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/ritsedejong\/\">Ritse de Jong<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-57407\" class=\"fusion-post-grid post-57407 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"547\" height=\"667\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2021\/08\/R9B3577-e1683534301849.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/stein\/\">\n\t\t\t\t\t\tStein de Boer\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/stein\/\" aria-label=\"Stein de Boer\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/stein\/\">Stein de Boer<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55360\" class=\"fusion-post-grid post-55360 post type-post status-publish format-standard has-post-thumbnail hentry category-classic category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"938\" height=\"1202\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959-200x256.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959-400x513.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959-600x769.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959-800x1025.jpg 800w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/07\/28-vegard-vik-new-e1746646296959.jpg 938w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/vegard\/\">\n\t\t\t\t\t\tVegard (international)\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/vegard\/\" aria-label=\"Vegard (international)\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/vegard\/\">Vegard (international)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-55371\" class=\"fusion-post-grid post-55371 post type-post status-publish format-standard has-post-thumbnail hentry category-faces category-faces-men\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"722\" height=\"1000\" src=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/06\/large-1717575008-cf42c27684275e6182dd840fb531f516.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/06\/large-1717575008-cf42c27684275e6182dd840fb531f516-200x277.jpg 200w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/06\/large-1717575008-cf42c27684275e6182dd840fb531f516-400x554.jpg 400w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/06\/large-1717575008-cf42c27684275e6182dd840fb531f516-600x831.jpg 600w, https:\/\/mattfaces.nl\/wp-content\/uploads\/2024\/06\/large-1717575008-cf42c27684275e6182dd840fb531f516.jpg 722w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 307px, (min-width: 732px) 460px, (min-width: 640px) 732px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/mattfaces.nl\/en\/yunus\/\">\n\t\t\t\t\t\tYunus T\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/mattfaces.nl\/en\/yunus\/\" aria-label=\"Yunus T\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/mattfaces.nl\/en\/yunus\/\">Yunus T<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_improvement_type_select":"improve_an_existing","_thumb_yes_seoaic":false,"_frame_yes_seoaic":false,"seoaic_generate_description":"","seoaic_improve_instructions_prompt":"","seoaic_rollback_content_improvement":"","seoaic_idea_thumbnail_generator":"","thumbnail_generated":false,"thumbnail_generate_prompt":"","seoaic_article_description":"","footnotes":""},"class_list":["post-52878","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Men - MattFaces<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mattfaces.nl\/en\/men\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Men - MattFaces\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mattfaces.nl\/en\/men\/\" \/>\n<meta property=\"og:site_name\" content=\"MattFaces\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T19:40:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/men\\\/\",\"url\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/men\\\/\",\"name\":\"Men - MattFaces\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#website\"},\"datePublished\":\"2017-04-29T10:43:03+00:00\",\"dateModified\":\"2025-12-16T19:40:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/men\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mattfaces.nl\\\/en\\\/men\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/men\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Men\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/\",\"name\":\"MattFaces\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#organization\",\"name\":\"MattFaces\",\"url\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mattfaces.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Mattfaces-favicon.png\",\"contentUrl\":\"https:\\\/\\\/mattfaces.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Mattfaces-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"MattFaces\"},\"image\":{\"@id\":\"https:\\\/\\\/mattfaces.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/matt_faces\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Men - MattFaces","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mattfaces.nl\/en\/men\/","og_locale":"en_US","og_type":"article","og_title":"Men - MattFaces","og_url":"https:\/\/mattfaces.nl\/en\/men\/","og_site_name":"MattFaces","article_modified_time":"2025-12-16T19:40:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mattfaces.nl\/en\/men\/","url":"https:\/\/mattfaces.nl\/en\/men\/","name":"Men - MattFaces","isPartOf":{"@id":"https:\/\/mattfaces.nl\/en\/#website"},"datePublished":"2017-04-29T10:43:03+00:00","dateModified":"2025-12-16T19:40:37+00:00","breadcrumb":{"@id":"https:\/\/mattfaces.nl\/en\/men\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mattfaces.nl\/en\/men\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mattfaces.nl\/en\/men\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mattfaces.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Men"}]},{"@type":"WebSite","@id":"https:\/\/mattfaces.nl\/en\/#website","url":"https:\/\/mattfaces.nl\/en\/","name":"MattFaces","description":"","publisher":{"@id":"https:\/\/mattfaces.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mattfaces.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mattfaces.nl\/en\/#organization","name":"MattFaces","url":"https:\/\/mattfaces.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mattfaces.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/10\/cropped-Mattfaces-favicon.png","contentUrl":"https:\/\/mattfaces.nl\/wp-content\/uploads\/2025\/10\/cropped-Mattfaces-favicon.png","width":512,"height":512,"caption":"MattFaces"},"image":{"@id":"https:\/\/mattfaces.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/matt_faces\/"]}]}},"_links":{"self":[{"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/pages\/52878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/comments?post=52878"}],"version-history":[{"count":2,"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/pages\/52878\/revisions"}],"predecessor-version":[{"id":52880,"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/pages\/52878\/revisions\/52880"}],"wp:attachment":[{"href":"https:\/\/mattfaces.nl\/en\/wp-json\/wp\/v2\/media?parent=52878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}